{"id":18934,"date":"2018-09-14T11:50:34","date_gmt":"2018-09-14T08:50:34","guid":{"rendered":"https:\/\/perfectvenue.es\/?p=18934"},"modified":"2018-10-03T11:18:00","modified_gmt":"2018-10-03T08:18:00","slug":"raquel-latorre-wedding-photographer-in-galicia","status":"publish","type":"post","link":"https:\/\/perfectvenue.es\/es\/2018\/09\/14\/raquel-latorre-wedding-photographer-in-galicia\/","title":{"rendered":"Entrevistamos a Raquel Latorre, fot\u00f3grafa de bodas en Galicia"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify\">Espa\u00f1a est\u00e1 repleta de lugares m\u00e1gicos donde celebrar una boda \u00fanica, y uno de ellos es Galicia. En esta zona del norte del pa\u00eds nos encontramos con Raquel Latorre, una fot\u00f3grafa de bodas capaz de captar esos instantes que los novios recordar\u00e1n para siempre del d\u00eda m\u00e1s importante de sus vidas.<\/p>\n<p style=\"text-align: justify\">Una de las razones por la que el trabajo de Raquel nos apasiona es por que logra el equilibrio perfecto entre su naturalidad y cercan\u00eda y la gran organizaci\u00f3n y detalle con los que se prepara para cada trabajo.<\/p>\n<p style=\"text-align: justify\">Nada mejor para conocerla m\u00e1s a fondo que a trav\u00e9s de esta interesante entrevista, en la que hemos recopilado las preguntas que m\u00e1s nos hac\u00e9is los novios de cara a escoger fot\u00f3grafo de bodas. Adem\u00e1s, os mostramos algunos de sus trabajos. As\u00ed que, si est\u00e1is buscando fot\u00f3grafa de bodas en Galicia, \u00a1no os lo perd\u00e1is!<\/p>\n<h3><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18985\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-5.jpg\" alt=\"Raquel Latorre wedding photographer in Galicia\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-5.jpg?v=1626108084 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-5-600x400.jpg?v=1626108084 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-5-300x200.jpg?v=1626108084 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-5-768x512.jpg?v=1626108084 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-5-450x300.jpg?v=1626108084 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/h3>\n<h3 style=\"text-align: justify\">Nos encantar\u00eda saber qu\u00e9 te llev\u00f3 a dedicarte al mundo de la fotograf\u00eda.<\/h3>\n<p style=\"text-align: justify\">Cuando era peque\u00f1a me impact\u00f3 una pel\u00edcula de indios y vaqueros en la que un indio, se negaba a ser fotografiado. Con mucho miedo en el cuerpo, explicaba que no quer\u00eda que su alma fuese robada y atrapada para siempre por aquella m\u00e1quina y permaneciese para la eternidad en un papel. Me fascin\u00f3 esa idea, me hizo pensar y fue cuando entend\u00ed lo que era y significaba el alma. Desde entonces siempre quise ser \u201ccazadora de almas\u201d, \u00a0conseguir captar ese instante, esa sonrisa, esa l\u00e1grima, esa expresi\u00f3n\u2026\u00a0que sea para siempre, que quede retratada en la retina y sea inmortal como el alma.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18984\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-4.jpg\" alt=\"Raquel Latorre wedding photographer in Galicia\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-4.jpg?v=1626108085 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-4-600x400.jpg?v=1626108085 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-4-300x200.jpg?v=1626108085 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-4-768x512.jpg?v=1626108085 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-4-450x300.jpg?v=1626108085 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">\u00bfC\u00f3mo consigues captar ese &#8220;alma&#8221; a trav\u00e9s de una fotograf\u00eda? \u00bfHay alguna clave?<\/h3>\n<p style=\"text-align: justify\">Dejando que todo fluya con naturalidad, me dejo llevar por los momentos, hacer que la pareja est\u00e9 c\u00f3moda y lleguen a ese momento en el que se olviden que hay una c\u00e1mara.\u00a0 Ah\u00ed, es cuando por fin sale la verdadera alma de la pareja, es cuando los momentos se hacen m\u00e1gicos. Y para ello hay que estar muy atenta a todo lo que ocurre y aplicando todos los conocimientos t\u00e9cnicos con agilidad y soltura.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18995\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-16.jpg\" alt=\"\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-16.jpg?v=1626108076 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-16-600x400.jpg?v=1626108076 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-16-300x200.jpg?v=1626108076 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-16-768x512.jpg?v=1626108076 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-16-450x300.jpg?v=1626108076 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">Disfrutas viendo feliz a la gente, \u00bfes una de las razones que te llevaron a ser fot\u00f3grafa de bodas?<\/h3>\n<p style=\"text-align: justify\">S\u00ed, me encanta ver feliz a la gente, hace que yo tambi\u00e9n lo sea. No s\u00e9 si esto influy\u00f3 para que terminase siendo fot\u00f3grafa de bodas, pero me siento muy feliz en las bodas, son momentos llenos de felicidad y con una alta dosis de emociones y ah\u00ed estoy, disfrutando en primera l\u00ednea, a la caza de almas.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18983\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-3.jpg\" alt=\"Raquel Latorre wedding photographer in Galicia\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-3.jpg?v=1626108086 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-3-600x400.jpg?v=1626108086 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-3-300x200.jpg?v=1626108086 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-3-768x512.jpg?v=1626108086 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-3-450x300.jpg?v=1626108086 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">Todos tenemos referentes, \u00bfhay alg\u00fan fot\u00f3grafo de bodas que te haya inspirado y al que admires? \u00bfPor qu\u00e9?<\/h3>\n<p style=\"text-align: justify\">No tengo un fot\u00f3grafo de cabecera. Siempre digo que hay que aprender de todos los fot\u00f3grafos y pintores, de los buenos y no tan buenos. Me inspiro en el conjunto de todas esas im\u00e1genes que veo y analizo. Cuando ves una gran fotograf\u00eda o un gran cuadro, te inspira, te lleva a querer cazar ese momento y trabajas todos los d\u00edas para conseguirlo.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18992\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-13.jpg\" alt=\"\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-13.jpg?v=1626108079 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-13-600x400.jpg?v=1626108079 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-13-300x200.jpg?v=1626108079 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-13-768x512.jpg?v=1626108079 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-13-450x300.jpg?v=1626108079 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">Imagino que realizar pre bodas es un plus, ya que puedes conectar con los novios antes de la boda y de una manera muy especial. Cu\u00e9ntanos un poco sobre este servicio, \u00bfcu\u00e1ntos meses antes de la boda se realiza? \u00bfAlg\u00fan lugar que recomiendes para ello?<\/h3>\n<p>Las Prebodas lo considero muy importante, fundamental. Es d\u00f3nde nos conocemos m\u00e1s a fondo, d\u00f3nde hablamos un poco de todo y de esta manera rompemos el hielo. Ven mi forma de fotografiar y ven los resultados de la sesi\u00f3n en pocos d\u00edas , se sienten tranquilos porque les gusta mucho el resultado y se dan cuenta que el d\u00eda se\u00f1alado har\u00e9 un buen trabajo. Esto hace que el d\u00eda de la boda no me vean como a la \u201cfot\u00f3grafa\u201d sino como a Raquel y parece que no, pero hay mucha diferencia de una boda con preboda y sin ella.<\/p>\n<p style=\"text-align: justify\">No tengo un tiempo estipulado para las Prebodas, cuando les venga mejor a la pareja y me avisen con tiempo suficiente para ajustar fechas. He realizado prebodas desde en bosques y playas hasta en medio de la ciudad. Lo importante siempre es que la pareja, en esta primera toma de contacto se sientas a gusto. Mi recomendaci\u00f3n es dar un peque\u00f1o paseo por el bosque para la sesi\u00f3n.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18993\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-14.jpg\" alt=\"\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-14.jpg?v=1626108078 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-14-600x400.jpg?v=1626108078 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-14-300x200.jpg?v=1626108078 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-14-768x512.jpg?v=1626108078 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-14-450x300.jpg?v=1626108078 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">\u00bfC\u00f3mo te preparas para una boda? Alg\u00fan m\u00e9todo que sigas, estructura, visitas al espacio, etc.<\/h3>\n<p style=\"text-align: justify\">D\u00edas antes confirmo que todos los horarios, direcciones sean los correctos. Si los recintos son cercanos me gusta visitarlos, de no ser as\u00ed, me informo por internet. El d\u00eda antes reviso y preparo todo el material y descanso todo lo que pueda, pues el d\u00eda siguiente ser\u00e1 un d\u00eda muy largo y duro f\u00edsicamente. Me gusta estar con tiempo de antelaci\u00f3n, en los sitios (nuca se sabe lo que puede pasar) y, sobre todo, con muchas ganas de empezar.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18988\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-9.jpg\" alt=\"Raquel Latorre wedding photographer in Galicia\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-9.jpg?v=1626108082 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-9-600x400.jpg?v=1626108082 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-9-300x200.jpg?v=1626108082 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-9-768x512.jpg?v=1626108082 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-9-450x300.jpg?v=1626108082 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">\u00bfQu\u00e9 objetivo te marcas a la hora de fotografiar una boda? \u00bfQu\u00e9 es lo que buscas conseguir?<\/h3>\n<p style=\"text-align: justify\">Mi objetivo en cada boda, como en la vida, es superarme, aprender cosas nuevas y conseguir que esa boda sea mejor que la anterior, la mejor de todas. Que mi \u201ccolecci\u00f3n de almas\u201d se ampl\u00ede e irme con una gran sonrisa de satisfacci\u00f3n a casa. Busco que la pareja dentro de 20, 30, 40 a\u00f1os cuando vuelvan a abrir el \u00e1lbum de su boda, regresen y sientan de nuevo esos momentos tan importantes para ellos.<\/p>\n<h3><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18986\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-6.jpg\" alt=\"Raquel Latorre wedding photographer in Galicia\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-6.jpg?v=1626108084 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-6-600x400.jpg?v=1626108084 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-6-300x200.jpg?v=1626108084 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-6-768x512.jpg?v=1626108084 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-6-450x300.jpg?v=1626108084 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/h3>\n<h3>\u00bfHay alg\u00fan lugar o regi\u00f3n que que te guste especialmente para realizar las fotograf\u00edas?<\/h3>\n<p style=\"text-align: justify\">Mi tierra, Galicia, para m\u00ed es fascinante, m\u00e1gica. Su verdor, sus gentes, su mar, su variedad de paisajes (desde la nieve al mar, desde la monta\u00f1a a las playas m\u00e1s espectaculares, desde sus pueblos rurales a las ciudades m\u00e1s modernas\u2026), siempre puedes tener el escenario perfecto para cada pareja. Aunque me atraen m\u00e1s los bosques, por su punto m\u00e1gico y sus tonalidades, puede ser que me inspire la parte \u201cmeiga\u201d \u00a0que tiene todo gallego, y de la que escribieron gente como Valle-Incl\u00e1n, Emilia Pardo Baz\u00e1n o Rosal\u00eda de Castro \u00f3 quiz\u00e1 ser\u00e1 porque en los bosques sale mi instinto de \u201ccazadora\u201d. Pero tambi\u00e9n quiero desplazarme a cualquier lugar del planeta, ya que el salir fuera de tu zona de confort te da m\u00e1s visi\u00f3n y nuevas expectativas.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18991\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-12.jpg\" alt=\"Raquel Latorre wedding photographer in Galicia\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-12.jpg?v=1626108079 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-12-600x400.jpg?v=1626108079 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-12-300x200.jpg?v=1626108079 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-12-768x512.jpg?v=1626108079 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-12-450x300.jpg?v=1626108079 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">\u00bfPor qu\u00e9 crees que has ido creciendo dentro del mundo de las bodas? \u00bfQu\u00e9 es lo que te hace diferente?<\/h3>\n<p style=\"text-align: justify\">He trabajado y trabajo muy duro cada d\u00eda, me preocupo por mi formaci\u00f3n y no paro hasta conseguir lo que quiero, t\u00e9cnicamente hablando. Soy muy apasionada y cabezona, emp\u00e1tica e intuitiva, activa y mi forma de ser influye de forma positiva en los resultados finales. Intento ir a una boda pensando que no son clientes, sino amigos y todo ello hace que el reportaje fluya de una forma especial. Estos ingredientes son buenos para un gran \u201cd\u00eda de caza\u201d. Lo que me hace diferente es mi forma especial de ver, de sentir, de hacer, de crear, que consigue que mi trabajo sea muy especial para las parejas.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18981\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-1.jpg\" alt=\"Raquel Latorre wedding photographer in Galicia\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-1.jpg?v=1626108087 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-1-600x400.jpg?v=1626108087 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-1-300x200.jpg?v=1626108087 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-1-768x512.jpg?v=1626108087 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-1-450x300.jpg?v=1626108087 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">Tienes un estilo propio pero, \u00bflo adaptas en funci\u00f3n de los gustos de tu cliente? \u00bfQu\u00e9 supone esto para un fot\u00f3grafo?<\/h3>\n<p style=\"text-align: justify\">Es muy importante saber cuales son los gustos del cliente (de ah\u00ed la importancia de la preboda), siempre te debes adaptar a las necesidades de cada pareja, pero manteniendo tu propio estilo. Eso no quiere decir que no evoluciones y te estanques, justamente lo contrario. Con cada boda aprendes algo nuevo y das un paso m\u00e1s. Esto es bueno porque puedes aplicar cosas nuevas a tu estilo y mejorarlo.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18997\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-18.jpg\" alt=\"\" width=\"780\" height=\"520\" srcset=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-18.jpg?v=1626108074 850w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-18-600x400.jpg?v=1626108074 600w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-18-300x200.jpg?v=1626108074 300w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-18-768x512.jpg?v=1626108074 768w, https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-in-galicia-18-450x300.jpg?v=1626108074 450w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">Y una pregunta m\u00e1s t\u00e9cnica para los amantes de la fotograf\u00eda, \u00bfqu\u00e9 equipo y software utilizas?<\/h3>\n<p style=\"text-align: justify\">Empleo principalmente dos c\u00e1maras, una a cada lado (\u201ccomo los vaqueros\u201d), con una lente fija en cada una de ellas. Las c\u00e1maras son Nikon D750 y las lentes fijas Nikon 85mm 1.8 y la otra 35mm 1.4. Adem\u00e1s siempre llevo en la bolsa 2 c\u00e1maras m\u00e1s con sus respectivas lentes de repuesto y una lente 105mm macro y un 14-24mm 2.8 para cosas puntuales. Para el baile llevo 2 flashes, y aunque no me gusta usarlos (prefiero siempre la luz natural), muchas veces son imprescindibles. Para la edici\u00f3n de las fotos empleo s\u00f3lo Lightroom, nada m\u00e1s. Me parece, en mi caso, innecesario emplear Photoshop ya que las buenas fotos salen de la c\u00e1mara.<\/p>\n<p><span class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18959\" src=\"https:\/\/perfectvenue.es\/wp-content\/uploads\/2018\/09\/raquel-latorre-wedding-photographer-7.jpg\" alt=\"Raquel Latorre wedding photographer\" width=\"780\" height=\"520\" \/><\/span><\/p>\n<h3 style=\"text-align: justify\">Por \u00faltimo, \u00bfqu\u00e9 tiempo de antelaci\u00f3n crees \u00f3ptimo para contactarte?<\/h3>\n<p style=\"text-align: justify\">Cuanto antes mejor, siempre puedes correr el riesgo de que luego no haya fechas. Considero que es una pena que si te gusta el trabajo de un fot\u00f3grafo, al final te quedes sin \u00e9l por no haberle dado prioridad. Lo primero que deber\u00edan concretar, una vez tienen decidida la fecha, es el fot\u00f3grafo ya que su trabajo es lo que van a perdurar despu\u00e9s de la boda para toda la vida. Como m\u00ednimo recomiendo que lo cierren con 6 meses de antelaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Si est\u00e1is buscando fot\u00f3grafa de bodas en Galicia y quer\u00e9is saber m\u00e1s sobre Raquel, en su <a href=\"https:\/\/www.raquellatorrefotografia.com\/\">web<\/a> pod\u00e9is ver todos sus trabajos. Tambi\u00e9n os recomendamos visitar su <a href=\"https:\/\/www.raquellatorrefotografia.com\/bodas\/\" target=\"_blank\" rel=\"noopener\">instagram<\/a> y ver las \u00faltimas novedades. \u00a1Much\u00edsimas gracias Raquel por tu tiempo!<\/p>\n<p><\/p>\n<span class=\"tags-links\"><a href=\"https:\/\/perfectvenue.es\/es\/tag\/boda-en-espana\/\" rel=\"tag\">boda en espa\u00f1a<\/a><a href=\"https:\/\/perfectvenue.es\/es\/tag\/bodas-en-galicia\/\" rel=\"tag\">bodas en galicia<\/a><a href=\"https:\/\/perfectvenue.es\/es\/tag\/destination-weddings\/\" rel=\"tag\">destination weddings<\/a><a href=\"https:\/\/perfectvenue.es\/es\/tag\/fotografa-de-bodas-en-galicia\/\" rel=\"tag\">fot\u00f3grafa de bodas en galicia<\/a><a href=\"https:\/\/perfectvenue.es\/es\/tag\/fotografia-de-bodas\/\" rel=\"tag\">fotograf\u00eda de bodas<\/a><a href=\"https:\/\/perfectvenue.es\/es\/tag\/wedding-photographer-in-galicia\/\" rel=\"tag\">wedding photographer in Galicia<\/a><\/span>","protected":false},"excerpt":{"rendered":"<p>Su fotograf\u00edas tienen alma y transmiten la magia que sucede cuando dos personas deciden celebrar su amor. Por esto y mucho m\u00e1s, hemos querido charlar con esta fot\u00f3grafa de bodas afincada en Galicia, que nos cuenta c\u00f3mo vive su trabajo y su experiencia en el sector.<\/p>\n","protected":false},"author":56,"featured_media":18987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[176],"tags":[496,942,757,941,935,966],"class_list":["post-18934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wedding","tag-boda-en-espana","tag-bodas-en-galicia","tag-destination-weddings","tag-fotografa-de-bodas-en-galicia","tag-fotografia-de-bodas","tag-wedding-photographer-in-galicia"],"_links":{"self":[{"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/posts\/18934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/comments?post=18934"}],"version-history":[{"count":0,"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/posts\/18934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/media\/18987"}],"wp:attachment":[{"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/media?parent=18934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/categories?post=18934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perfectvenue.es\/es\/wp-json\/wp\/v2\/tags?post=18934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}